{"id":9380,"date":"2022-03-11T05:42:18","date_gmt":"2022-03-11T05:42:18","guid":{"rendered":"https:\/\/uglyshuzz.com\/?page_id=9380"},"modified":"2025-10-24T05:31:36","modified_gmt":"2025-10-24T05:31:36","slug":"%d7%90%d6%b7%d7%92%d6%b0%d7%9c%d6%b4%d7%99%d7%a9%d7%81%d7%95%d6%b9%d7%96-2","status":"publish","type":"page","link":"https:\/\/uglyshuzz.com\/he_il\/","title":{"rendered":"\u05d1\u05d9\u05ea"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9380\" class=\"elementor elementor-9380\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e1d9b0 elementor-section-full_width elementor-section-stretched elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"4e1d9b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-156c13b\" data-id=\"156c13b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-194e258 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"194e258\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u05e1\u05dc\u05d9\u05d9\u05d3\u05d9\u05dd\" dir=\"rtl\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-4fa04b5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--out\" role=\"img\" aria-label=\"doubleboxed_241703432_121460713575727_3860033162499933072_n\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">NIKE DUNK COLLECTION<\/div><a href=\"https:\/\/legitshoes.co.il\/product-category\/nike\/nike-dunk\/\" class=\"elementor-button elementor-slide-button elementor-size-sm\">\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 \u2190 <\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-235f54e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"doubleboxed_257484060_294228499226283_202839807751027041_n\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">AIR JORDAN 1 COLLECTION<\/div><a href=\"https:\/\/legitshoes.co.il\/product-category\/jordan\/air-jordan-1\/\" class=\"elementor-button elementor-slide-button elementor-size-sm\">\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4  \u2190 <\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"\u05e9\u05e7\u05d5\u05e4\u05d9\u05ea \u05e7\u05d5\u05d3\u05de\u05ea\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"\u05e9\u05e7\u05d5\u05e4\u05d9\u05ea \u05d4\u05d1\u05d0\u05d4\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eabbb2e elementor-section-stretched elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eabbb2e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1745ec5\" data-id=\"1745ec5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54a13ae elementor--h-position-left elementor--v-position-bottom elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"54a13ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u05e1\u05dc\u05d9\u05d9\u05d3\u05d9\u05dd\" dir=\"rtl\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-4fa04b5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--out\" role=\"img\" aria-label=\"crepcured_292363363_557083039194806_9212856200706611292_n\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">NIKE DUNK COLLECTION<\/div><a href=\"https:\/\/legitshoes.co.il\/product-category\/nike\/nike-dunk\/\" class=\"elementor-button elementor-slide-button elementor-size-sm\">\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 \u2190 <\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ded6247\" data-id=\"ded6247\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa331a elementor--h-position-left elementor--v-position-bottom elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"caa331a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u05e1\u05dc\u05d9\u05d9\u05d3\u05d9\u05dd\" dir=\"rtl\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-4fa04b5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"uglyshuz.il_280773635_2053180748188436_4249005530757935394_n\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">AIR JORDAN 1 COLLECTION<\/div><a href=\"https:\/\/legitshoes.co.il\/product-category\/jordan\/air-jordan-1\/\" class=\"elementor-button elementor-slide-button elementor-size-sm\">\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 \u2190 <\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75d94c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75d94c0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3581287\" data-id=\"3581287\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a1530d elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"2a1530d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-86b8b13\" data-id=\"86b8b13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2db3f70 elementor-widget elementor-widget-image\" data-id=\"2db3f70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"123\" height=\"123\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2022\/04\/3.png\" class=\"attachment-full size-full wp-image-11616\" alt=\"\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2022\/04\/3.png 123w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2022\/04\/3-100x100.png 100w\" sizes=\"(max-width: 123px) 100vw, 123px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-b3ff843\" data-id=\"b3ff843\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-693335e elementor-widget elementor-widget-heading\" data-id=\"693335e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">20,000 + \u05dc\u05e7\u05d5\u05d7\u05d5\u05ea \u05de\u05e8\u05d5\u05e6\u05d9\u05dd \u05d5\u05d7\u05d5\u05d6\u05e8\u05d9\u05dd<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9f5c0c8\" data-id=\"9f5c0c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ed7877 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ed7877\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-247b4de\" data-id=\"247b4de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09404cc elementor-widget elementor-widget-image\" data-id=\"09404cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"123\" height=\"123\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2022\/04\/2.png\" class=\"attachment-full size-full wp-image-11618\" alt=\"\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2022\/04\/2.png 123w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2022\/04\/2-100x100.png 100w\" sizes=\"(max-width: 123px) 100vw, 123px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-a627af1\" data-id=\"a627af1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de5fd8e elementor-widget elementor-widget-heading\" data-id=\"de5fd8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a05 \u05e9\u05e0\u05d5\u05ea \u05e0\u05d9\u05e1\u05d9\u05d5\u05df \u05de2017 \u05d7\u05d1\u05e8\u05d4 \u05d1\u05e2\u05f4\u05de<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f0da5b1\" data-id=\"f0da5b1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43ce80d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43ce80d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e6ed42a\" data-id=\"e6ed42a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9723da6 elementor-widget elementor-widget-image\" data-id=\"9723da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"125\" height=\"123\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2022\/04\/1.png\" class=\"attachment-full size-full wp-image-11617\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-5f85525\" data-id=\"5f85525\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2519e1d elementor-widget elementor-widget-heading\" data-id=\"2519e1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u05e8\u05db\u05d9\u05e9\u05d4 \u05de\u05d0\u05d5\u05d1\u05d8\u05d7\u05ea PCI , \u05e0\u05d5\u05d7\u05d4 \u05d5\u05e7\u05dc\u05d4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e102fd3\" data-id=\"e102fd3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6446e94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6446e94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d7dadca\" data-id=\"d7dadca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-467fade elementor-widget elementor-widget-image\" data-id=\"467fade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"134\" height=\"134\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2021\/04\/\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-01.png\" class=\"attachment-full size-full wp-image-1492\" alt=\"Customer service\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2021\/04\/\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-01.png 134w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2021\/04\/\u05d0\u05d9\u05d9\u05e7\u05d5\u05df-01-100x100.png 100w\" sizes=\"(max-width: 134px) 100vw, 134px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-f8d264d\" data-id=\"f8d264d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4f2121 elementor-widget elementor-widget-heading\" data-id=\"b4f2121\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u05e9\u05d9\u05e8\u05d5\u05ea \u05dc\u05e7\u05d5\u05d7\u05d5\u05ea \u05d6\u05de\u05d9\u05df \u05d5\u05de\u05d4\u05d9\u05e8 \u05d1\u05de\u05d9\u05d5\u05d7\u05d3<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4941113 elementor-section-full_width viewall-button elementor-section-height-default elementor-section-height-default\" data-id=\"4941113\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b4c0c9\" data-id=\"4b4c0c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-199bcc0 elementor-widget elementor-widget-button\" data-id=\"199bcc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uglyshuzz.com\/product-category\/best-seller\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View All<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-352fb30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"352fb30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aae7caf\" data-id=\"aae7caf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ee53c3 elementor-grid-4 elementor-grid-tablet-3 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"7ee53c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-4 \">\r\n<ul class=\"products elementor-grid oceanwp-row clr grid\">\r\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal has-no-thumbnails product type-product post-22809 status-publish first instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-big-buckle-natural-leather-nubuck-beige\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-300x180.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Big Buckle Natural Leather Nubuck Beige \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22809\" class=\"owp-quick-view\" data-product_id=\"22809\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Big Buckle Natural Leather Nubuck Beige \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-big-buckle-natural-leather-nubuck-beige\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-300x180.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Big Buckle Natural Leather Nubuck Beige \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/74-1.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22809\" class=\"owp-quick-view\" data-product_id=\"22809\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Big Buckle Natural Leather Nubuck Beige \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-big-buckle-natural-leather-nubuck-beige\/\">\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Big Buckle Natural Leather Nubuck Beige \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8<\/a><\/h2><\/li><li class=\"price-wrap\">\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-big-buckle-natural-leather-nubuck-beige\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22809\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22809\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Big Buckle Natural Leather Nubuck Beige \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22809\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22796 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-dark-brown-%d7%a2%d7%9d-%d7%a0\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-300x180.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-300x180.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22796\" class=\"owp-quick-view\" data-product_id=\"22796\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-dark-brown-%d7%a2%d7%9d-%d7%a0\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-300x180.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-14-1.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-300x180.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-15-1.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22796\" class=\"owp-quick-view\" data-product_id=\"22796\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-dark-brown-%d7%a2%d7%9d-%d7%a0\/\">\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>439.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-dark-brown-%d7%a2%d7%9d-%d7%a0\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22796\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22796\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor Dark Brown \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22796\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22783 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-white-%d7%a2%d7%9d-%d7%a0%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-300x180.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-300x180.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22783\" class=\"owp-quick-view\" data-product_id=\"22783\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-white-%d7%a2%d7%9d-%d7%a0%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-300x180.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-7.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-300x180.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-300x180.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-1024x614.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-768x461.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9-600x360.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/207-9.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22783\" class=\"owp-quick-view\" data-product_id=\"22783\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-white-%d7%a2%d7%9d-%d7%a0%d7%a2\/\">\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>439.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%9b%d7%a4%d7%9b%d7%a4%d7%99-%d7%91%d7%99%d7%a8%d7%a7%d7%a0%d7%a9%d7%98%d7%95%d7%a7-%d7%a0%d7%a9%d7%99%d7%9d-birkenstock-madrid-birko-flor-white-%d7%a2%d7%9d-%d7%a0%d7%a2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22783\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22783\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05db\u05e4\u05db\u05e4\u05d9 \u05d1\u05d9\u05e8\u05e7\u05e0\u05e9\u05d8\u05d5\u05e7 \u05e0\u05e9\u05d9\u05dd Birkenstock Madrid Birko-Flor White \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05dc\u05d9\u05dc\u05d3\u05d9\u05dd&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22783\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22765 status-publish last instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22765\" class=\"owp-quick-view\" data-product_id=\"22765\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537_32a8aaf6-aea9-495c-9764-bf6b2c.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0501537-1_7d3e0c45-610a-4ad1-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22765\" class=\"owp-quick-view\" data-product_id=\"22765\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99\/\">\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22765\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22765\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22765\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22750 status-publish first instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22750\" class=\"owp-quick-view\" data-product_id=\"22750\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106CP0502429-1-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22750\" class=\"owp-quick-view\" data-product_id=\"22750\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\">\u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-campo-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22750\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22750\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: Veja Campo \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22750\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22740 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%98%d7%91%d7%a2%d7%95%d7%a0%d7%99%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-v-10-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22740\" class=\"owp-quick-view\" data-product_id=\"22740\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%98%d7%91%d7%a2%d7%95%d7%a0%d7%99%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-v-10-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106VX0702892A03-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22740\" class=\"owp-quick-view\" data-product_id=\"22740\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%98%d7%91%d7%a2%d7%95%d7%a0%d7%99%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-v-10-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0\/\">\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%98%d7%91%d7%a2%d7%95%d7%a0%d7%99%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-v-10-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22740\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22740\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d8\u05d1\u05e2\u05d5\u05e0\u05d9\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd V-10 \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22740\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22726 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-recife-%d7%a2%d7%9d-%d7%9e%d7%a9%d7%9c%d7%95%d7%97-%d7%9e%d7%94%d7%99%d7%a8-%d7%9c%d7%9b%d7%9c-%d7%94%d7%90%d7%a8%d7%a5\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22726\" class=\"owp-quick-view\" data-product_id=\"22726\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-recife-%d7%a2%d7%9d-%d7%9e%d7%a9%d7%9c%d7%95%d7%97-%d7%9e%d7%94%d7%99%d7%a8-%d7%9c%d7%9b%d7%9c-%d7%94%d7%90%d7%a8%d7%a5\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/123-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22726\" class=\"owp-quick-view\" data-product_id=\"22726\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-recife-%d7%a2%d7%9d-%d7%9e%d7%a9%d7%9c%d7%95%d7%97-%d7%9e%d7%94%d7%99%d7%a8-%d7%9c%d7%9b%d7%9c-%d7%94%d7%90%d7%a8%d7%a5\/\">\u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-recife-%d7%a2%d7%9d-%d7%9e%d7%a9%d7%9c%d7%95%d7%97-%d7%9e%d7%94%d7%99%d7%a8-%d7%9c%d7%9b%d7%9c-%d7%94%d7%90%d7%a8%d7%a5\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22726\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22726\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: Veja Recife \u05e2\u05dd \u05de\u05e9\u05dc\u05d5\u05d7 \u05de\u05d4\u05d9\u05e8 \u05dc\u05db\u05dc \u05d4\u05d0\u05e8\u05e5&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22726\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22709 status-publish last instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22709\" class=\"owp-quick-view\" data-product_id=\"22709\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/66666-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22709\" class=\"owp-quick-view\" data-product_id=\"22709\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\">\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95%d7%aa-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22709\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22709\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22709\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22698 status-publish first instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22698\" class=\"owp-quick-view\" data-product_id=\"22698\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/888-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22698\" class=\"owp-quick-view\" data-product_id=\"22698\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%a2\/\">\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%90%d7%95%d7%a4%d7%a0%d7%aa-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%a2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22698\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22698\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05d0\u05d5\u05e4\u05e0\u05ea \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05e2\u05db\u05e9\u05d5\u05d5\u05d9\u05ea&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22698\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22687 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-1024x888.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-768x666.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2.png 1045w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-1024x888.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-768x666.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1.png 1045w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22687\" class=\"owp-quick-view\" data-product_id=\"22687\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-1024x888.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-768x666.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-2.png 1045w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-1024x888.png 1024w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-768x666.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/444ll5-1.png 1045w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22687\" class=\"owp-quick-view\" data-product_id=\"22687\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\">\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%91%d7%9e%d7%91%d7%a6%d7%a2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22687\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22687\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd Veja Campo \u05e2\u05dd \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d1\u05e6\u05e2&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22687\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22676 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%a7%d7%a0%d7%91%d7%a1-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2%d7%9c%d7%99\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22676\" class=\"owp-quick-view\" data-product_id=\"22676\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%a7%d7%a0%d7%91%d7%a1-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2%d7%9c%d7%99\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/kk12-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22676\" class=\"owp-quick-view\" data-product_id=\"22676\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%a7%d7%a0%d7%91%d7%a1-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2%d7%9c%d7%99\/\">\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%a7%d7%a0%d7%91%d7%a1-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-veja-campo-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2%d7%9c%d7%99\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22676\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22676\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05e7\u05e0\u05d1\u05e1 \u05dc\u05e0\u05e9\u05d9\u05dd Veja Campo \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d1\u05d9\u05e0\u05dc\u05d0\u05d5\u05de\u05d9\u05d9\u05dd&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22676\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22661 status-publish last instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a1%d7%a4%d7%95%d7%a8%d7%98\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22661\" class=\"owp-quick-view\" data-product_id=\"22661\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a1%d7%a4%d7%95%d7%a8%d7%98\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/hg444-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22661\" class=\"owp-quick-view\" data-product_id=\"22661\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a1%d7%a4%d7%95%d7%a8%d7%98\/\">\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-v-10-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a1%d7%a4%d7%95%d7%a8%d7%98\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22661\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22661\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: Veja V-10 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e4\u05d5\u05e8\u05d8&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22661\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22645 status-publish first instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%98%d7%a8%d7%a0%d7%93%d7%99%d7%95%d7%aa\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22645\" class=\"owp-quick-view\" data-product_id=\"22645\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%98%d7%a8%d7%a0%d7%93%d7%99%d7%95%d7%aa\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/131-4.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22645\" class=\"owp-quick-view\" data-product_id=\"22645\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%98%d7%a8%d7%a0%d7%93%d7%99%d7%95%d7%aa\/\">\u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%98%d7%a8%d7%a0%d7%93%d7%99%d7%95%d7%aa\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22645\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22645\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d8\u05e8\u05e0\u05d3\u05d9\u05d5\u05ea&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22645\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22629 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a8%d7%97%d7%95%d7%91-%d7%9e%d7%a2%d7%95%d7%a6%d7%91%d7%95%d7%aa\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22629\" class=\"owp-quick-view\" data-product_id=\"22629\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a8%d7%97%d7%95%d7%91-%d7%9e%d7%a2%d7%95%d7%a6%d7%91%d7%95%d7%aa\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/VEJA_SS24_NM_VOLLEY_HD_43-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22629\" class=\"owp-quick-view\" data-product_id=\"22629\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a8%d7%97%d7%95%d7%91-%d7%9e%d7%a2%d7%95%d7%a6%d7%91%d7%95%d7%aa\/\">\u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-veja-volley-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99-%d7%a8%d7%97%d7%95%d7%91-%d7%9e%d7%a2%d7%95%d7%a6%d7%91%d7%95%d7%aa\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22629\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22629\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: Veja Volley \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9 \u05e8\u05d7\u05d5\u05d1 \u05de\u05e2\u05d5\u05e6\u05d1\u05d5\u05ea&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22629\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22618 status-publish instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-v-12-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22618\" class=\"owp-quick-view\" data-product_id=\"22618\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-v-12-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1--600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/106XD0202336B15-1-.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22618\" class=\"owp-quick-view\" data-product_id=\"22618\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-v-12-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95\/\">\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%9c%d7%92%d7%91%d7%a8%d7%99%d7%9d-v-12-%d7%a2%d7%9d-%d7%a0%d7%a2%d7%9c%d7%99%d7%99%d7%9d-%d7%90%d7%99%d7%9b%d7%95%d7%aa%d7%99%d7%95\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22618\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22618\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05dc\u05d2\u05d1\u05e8\u05d9\u05dd V-12 \u05e2\u05dd \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05d0\u05d9\u05db\u05d5\u05ea\u05d9\u05d5\u05ea \u05d1\u05de\u05d1\u05e6\u05e2&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22618\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<li class=\"entry has-media has-product-nav col span_1_of_4 owp-content-center owp-thumbs-layout-horizontal owp-btn-normal owp-tabs-layout-horizontal product type-product post-22608 status-publish last instock has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n\t<div class=\"product-inner clr\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%92%d7%91%d7%95%d7%94%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-minotaur-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22608\" class=\"owp-quick-view\" data-product_id=\"22608\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<ul class=\"woo-entry-inner clr\"><li class=\"image-wrap\">\r\n\t<div class=\"woo-entry-image-swap woo-entry-image clr\">\r\n\t\t<a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%92%d7%91%d7%95%d7%94%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-minotaur-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2\/\" class=\"woocommerce-LoopProduct-link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-300x260.png\" class=\"woo-entry-image-main\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-1.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"260\" src=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-300x260.png\" class=\"woo-entry-image-secondary\" alt=\"\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd\" itemprop=\"image\" srcset=\"https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-300x260.png 300w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-768x665.png 768w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2-600x520.png 600w, https:\/\/uglyshuzz.com\/wp-content\/uploads\/2025\/08\/5655011-2.png 882w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"#\" id=\"product_id_22608\" class=\"owp-quick-view\" data-product_id=\"22608\" aria-label=\"Quickly preview product \u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd\"><i class=\" icon-eye\" aria-hidden=\"true\" role=\"img\"><\/i> \u05e6\u05e4\u05d9\u05d9\u05d4 \u05de\u05d4\u05d9\u05e8\u05d4<\/a>\t<\/div><!-- .woo-entry-image-swap -->\r\n\r\n<\/li><li class=\"title\"><h2><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%92%d7%91%d7%95%d7%94%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-minotaur-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2\/\">\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd<\/a><\/h2><\/li><li class=\"price-wrap\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#8362;<\/span>479.00<\/bdi><\/span><\/span>\n<\/li><li class=\"rating\"><\/li><li class=\"btn-wrap clr\"><a href=\"https:\/\/uglyshuzz.com\/he_il\/product\/%d7%9e%d7%91%d7%a6%d7%a2-%d7%a1%d7%a0%d7%99%d7%a7%d7%a8%d7%a1-%d7%92%d7%91%d7%95%d7%94%d7%95%d7%aa-%d7%9c%d7%a0%d7%a9%d7%99%d7%9d-minotaur-%d7%a2%d7%9d-%d7%9e%d7%95%d7%aa%d7%92%d7%99-%d7%a0%d7%a2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_22608\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"22608\" data-product_sku=\"\" aria-label=\"\u05d4\u05e6\u05d2\u05ea \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05e2\u05d1\u05d5\u05e8 &quot;\u05de\u05d1\u05e6\u05e2: \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d2\u05d1\u05d5\u05d4\u05d5\u05ea \u05dc\u05e0\u05e9\u05d9\u05dd Minotaur \u05e2\u05dd \u05de\u05d5\u05ea\u05d2\u05d9 \u05e0\u05e2\u05dc\u05d9\u05d9\u05dd \u05de\u05d5\u05d1\u05d9\u05dc\u05d9\u05dd&quot;\" rel=\"nofollow\">\u05d1\u05d7\u05e8 \u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22608\" class=\"screen-reader-text\">\n\t\t\u05dc\u05de\u05d5\u05e6\u05e8 \u05d6\u05d4 \u05d9\u05e9 \u05de\u05e1\u05e4\u05e8 \u05e1\u05d5\u05d2\u05d9\u05dd. \u05e0\u05d9\u05ea\u05df \u05dc\u05d1\u05d7\u05d5\u05e8 \u05d0\u05ea \u05d4\u05d0\u05e4\u05e9\u05e8\u05d5\u05d9\u05d5\u05ea \u05d1\u05e2\u05de\u05d5\u05d3 \u05d4\u05de\u05d5\u05e6\u05e8\t<\/span>\n<\/li><\/ul><\/div><!-- .product-inner .clr --><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d63300b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"d63300b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-febb638\" data-id=\"febb638\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80167f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80167f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-323d897\" data-id=\"323d897\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b9492a elementor-widget elementor-widget-heading\" data-id=\"9b9492a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">AIR JORDAN 1 <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2554133 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2554133\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uglyshuzz.com\/he_il\/product-category\/air-jordan\/air-jordan-1-high\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u05dc\u05db\u05e0\u05d9\u05e1\u05d4 \u05dc\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be47c2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be47c2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e94178\" data-id=\"4e94178\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ab2538 elementor-section-full_width viewall-button elementor-section-height-default elementor-section-height-default\" data-id=\"0ab2538\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd1e84a\" data-id=\"bd1e84a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9485b04 elementor-widget elementor-widget-button\" data-id=\"9485b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uglyshuzz.com\/product-category\/nike-air-jordan-1-collection\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View All<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e255469 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e255469\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06a7698\" data-id=\"06a7698\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d850fa7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d850fa7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c201d43\" data-id=\"c201d43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d2a006 elementor-widget elementor-widget-heading\" data-id=\"2d2a006\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">NIKE DUNK<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4348579 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4348579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uglyshuzz.com\/he_il\/product-category\/%d7%a0%d7%a2%d7%9c%d7%99-%d7%a0%d7%99%d7%99%d7%a7-%d7%9c%d7%9e%d7%9b%d7%99%d7%a8%d7%94\/%d7%a0%d7%99%d7%99%d7%a7-%d7%93%d7%90%d7%a0%d7%a7-%d7%9c%d7%9e%d7%9b%d7%99%d7%a8%d7%94\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u05dc\u05db\u05e0\u05d9\u05e1\u05d4 \u05dc\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbd0f25 elementor-section-full_width viewall-button elementor-section-height-default elementor-section-height-default\" data-id=\"cbd0f25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3dd6f5\" data-id=\"d3dd6f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07dbaa3 elementor-widget elementor-widget-button\" data-id=\"07dbaa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uglyshuzz.com\/product-category\/%d7%a0%d7%a2%d7%9c%d7%99-%d7%a0%d7%99%d7%99%d7%a7-%d7%9c%d7%9e%d7%9b%d7%99%d7%a8%d7%94\/%d7%a0%d7%99%d7%99%d7%a7-%d7%93%d7%90%d7%a0%d7%a7-%d7%9c%d7%9e%d7%9b%d7%99%d7%a8%d7%94\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View All<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b4fdc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b4fdc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d41c98f\" data-id=\"d41c98f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3991375 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3991375\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b16a66\" data-id=\"4b16a66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-677ec02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"677ec02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dd0379e\" data-id=\"dd0379e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2701a1 elementor-widget elementor-widget-heading\" data-id=\"b2701a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">YEEZY SLIDE <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-20a5117 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"20a5117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uglyshuzz.com\/he_il\/product-category\/%d7%a0%d7%a2%d7%9c%d7%99-%d7%99%d7%99%d7%96%d7%99-%d7%9c%d7%9e%d7%9b%d7%99%d7%a8%d7%94\/yeezy-slide\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u05dc\u05db\u05e0\u05d9\u05e1\u05d4 \u05dc\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9c042d elementor-section-full_width viewall-button elementor-section-height-default elementor-section-height-default\" data-id=\"d9c042d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c36e5fe\" data-id=\"c36e5fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-215ed67 elementor-widget elementor-widget-button\" data-id=\"215ed67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uglyshuzz.com\/product-category\/%d7%a0%d7%a2%d7%9c%d7%99-%d7%99%d7%99%d7%96%d7%99-%d7%9c%d7%9e%d7%9b%d7%99%d7%a8%d7%94\/yeezy-350\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View All<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-118e76d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"118e76d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d05d38d\" data-id=\"d05d38d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f550975 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f550975\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29084d0\" data-id=\"29084d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4271cd7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4271cd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae97572\" data-id=\"ae97572\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ff0a54 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ff0a54\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0064f5c\" data-id=\"0064f5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-537b443 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"537b443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0255aca\" data-id=\"0255aca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d070310 elementor-widget elementor-widget-heading\" data-id=\"d070310\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u05d0\u05e0\u05d7\u05e0\u05d5 \u05d1\u05d0\u05d9\u05e0\u05e1\u05d8\u05d2\u05e8\u05dd <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bebf16d\" data-id=\"bebf16d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-978285f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"978285f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29f9449 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29f9449\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-959c672\" data-id=\"959c672\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5444e32 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5444e32\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fafa69f\" data-id=\"fafa69f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1156117 elementor-widget elementor-widget-toggle\" data-id=\"1156117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1811\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-left\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 127.338v257.324c0 17.818-21.543 26.741-34.142 14.142L29.196 270.142c-7.81-7.81-7.81-20.474 0-28.284l128.662-128.662c12.599-12.6 34.142-3.676 34.142 14.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u05d0\u05d9\u05e4\u05d4 \u05d0\u05e0\u05d9 \u05d9\u05db\u05d5\u05dc \u05dc\u05e7\u05e0\u05d5\u05ea \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d7\u05d9\u05e8 \u05d4\u05de\u05e9\u05ea\u05dc\u05dd \u05d1\u05d9\u05d5\u05ea\u05e8?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1811\"><p>\u05d0\u05dd \u05d0\u05ea\u05d4 \u05de\u05d7\u05e4\u05e9 \u05d7\u05e0\u05d5\u05ea \u05d0\u05d5\u05e0\u05dc\u05d9\u05d9\u05df \u05dc\u05e0\u05e2\u05dc\u05d9 \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1 \u05d1\u05de\u05d7\u05d9\u05e8\u05d9\u05dd \u05de\u05e9\u05ea\u05dc\u05de\u05d9\u05dd, \u05dc\u05d0 \u05ea\u05d5\u05db\u05dc\u05d5 \u05dc\u05de\u05e6\u05d5\u05d0 \u05d9\u05d5\u05ea\u05e8 \u05d8\u05d5\u05d1 \u05de\u05d0\u05b7\u05d2\u05b0\u05dc\u05b4\u05d9\u05e9\u05c1\u05d5\u05b9\u05d6, \u05d4\u05d7\u05e0\u05d5\u05ea \u05d4\u05de\u05d5\u05d1\u05d9\u05dc\u05d4 \u05d1\u05ea\u05d7\u05d5\u05dd \u05de\u05db\u05d9\u05e8\u05ea \u05e0\u05e2\u05dc\u05d9 \u05e1\u05e0\u05d9\u05e7\u05e8\u05e1. \u05e8\u05d5\u05e6\u05d4 \u05dc\u05e0\u05e2\u05d5\u05dc \u05e0\u05e2\u05dc\u05d9 \u05d2'\u05d5\u05e8\u05d3\u05df \u05d7\u05d3\u05e9\u05d5\u05ea \u05d1\u05e1\u05d8\u05d9\u05d9\u05dc \u05d9\u05d5\u05dd \u05d9\u05d5\u05de\u05d9? \u05d4\u05d6\u05de\u05d9\u05e0\u05d5 \u05e2\u05d5\u05d3 \u05d4\u05d9\u05d5\u05dd!<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1812\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1812\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-left\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 127.338v257.324c0 17.818-21.543 26.741-34.142 14.142L29.196 270.142c-7.81-7.81-7.81-20.474 0-28.284l128.662-128.662c12.599-12.6 34.142-3.676 34.142 14.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u05db\u05de\u05d4 \u05d6\u05de\u05df \u05d9\u05e7\u05d7 \u05dc\u05d0\u05b7\u05d2\u05b0\u05dc\u05b4\u05d9\u05e9\u05c1\u05d5\u05b9\u05d6 \u05dc\u05d4\u05d1\u05d9\u05d0 \u05dc\u05d9 \u05d0\u05ea \u05d4\u05d4\u05d6\u05de\u05e0\u05d5\u05ea \u05e9\u05dc\u05d9?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1812\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1812\"><p>\u05d4\u05e6\u05d5\u05d5\u05ea \u05e9\u05dc\u05e0\u05d5 \u05e2\u05d5\u05e9\u05d4 \u05d0\u05ea \u05db\u05dc \u05d4\u05de\u05d0\u05de\u05e6\u05d9\u05dd \u05e2\u05dc \u05de\u05e0\u05ea \u05dc\u05e9\u05dc\u05d5\u05d7 \u05d0\u05ea \u05d4\u05d4\u05d6\u05de\u05e0\u05d4 \u05e9\u05dc\u05da \u05dc\u05d3\u05dc\u05ea \u05d1\u05d9\u05ea\u05da \u05d1\u05d4\u05e7\u05d3\u05dd \u05d4\u05d0\u05e4\u05e9\u05e8\u05d9. \u05d0\u05e0\u05d7\u05e0\u05d5 \u05de\u05d1\u05d8\u05d9\u05d7\u05d9\u05dd \u05e9\u05d4\u05d6\u05de\u05e0\u05ea\u05da \u05ea\u05e9\u05dc\u05d7 \u05e2\u05d3 24 \u05e9\u05e2\u05d5\u05ea \u05de\u05d9\u05d5\u05dd \u05d1\u05d9\u05e6\u05d5\u05e2 \u05d4\u05d4\u05d6\u05de\u05e0\u05d4, \u05d0\u05d1\u05dc \u05d6\u05d4 \u05d9\u05db\u05d5\u05dc \u05dc\u05e7\u05d7\u05ea \u05d1\u05d9\u05df 6 \u05dc19\u00a0 \u05d9\u05de\u05d9 \u05e2\u05e1\u05e7\u05d9\u05dd \u05e2\u05d3 \u05e9\u05d6\u05d4 \u05de\u05d2\u05d9\u05e2 \u05d0\u05dc\u05d9\u05d9\u05da \u05e2\u05d3 \u05d4\u05d1\u05d9\u05ea. \u05ea\u05d5\u05db\u05dc \u05d2\u05dd \u05dc\u05d9\u05e6\u05d5\u05e8 \u05e7\u05e9\u05e8 \u05e2\u05dd \u05e9\u05d9\u05e8\u05d5\u05ea \u05d4\u05dc\u05e7\u05d5\u05d7\u05d5\u05ea \u05e9\u05dc\u05e0\u05d5 \u05e2\u05dc \u05de\u05e0\u05ea \u05dc\u05d4\u05d1\u05d8\u05d9\u05d7 \u05e9\u05db\u05dc \u05d4\u05d7\u05e9\u05e9\u05d5\u05ea \u05e9\u05dc\u05da \u05dc\u05d2\u05d1\u05d9 \u05d4\u05de\u05e9\u05dc\u05d5\u05d7 \u05d9\u05e2\u05dc\u05de\u05d5\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"\\u05d0\\u05d9\\u05e4\\u05d4 \\u05d0\\u05e0\\u05d9 \\u05d9\\u05db\\u05d5\\u05dc \\u05dc\\u05e7\\u05e0\\u05d5\\u05ea \\u05e0\\u05e2\\u05dc\\u05d9 \\u05e1\\u05e0\\u05d9\\u05e7\\u05e8\\u05e1 \\u05d1\\u05de\\u05d7\\u05d9\\u05e8 \\u05d4\\u05de\\u05e9\\u05ea\\u05dc\\u05dd \\u05d1\\u05d9\\u05d5\\u05ea\\u05e8?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>\\u05d0\\u05dd \\u05d0\\u05ea\\u05d4 \\u05de\\u05d7\\u05e4\\u05e9 \\u05d7\\u05e0\\u05d5\\u05ea \\u05d0\\u05d5\\u05e0\\u05dc\\u05d9\\u05d9\\u05df \\u05dc\\u05e0\\u05e2\\u05dc\\u05d9 \\u05e1\\u05e0\\u05d9\\u05e7\\u05e8\\u05e1 \\u05d1\\u05de\\u05d7\\u05d9\\u05e8\\u05d9\\u05dd \\u05de\\u05e9\\u05ea\\u05dc\\u05de\\u05d9\\u05dd, \\u05dc\\u05d0 \\u05ea\\u05d5\\u05db\\u05dc\\u05d5 \\u05dc\\u05de\\u05e6\\u05d5\\u05d0 \\u05d9\\u05d5\\u05ea\\u05e8 \\u05d8\\u05d5\\u05d1 \\u05de\\u05d0\\u05b7\\u05d2\\u05b0\\u05dc\\u05b4\\u05d9\\u05e9\\u05c1\\u05d5\\u05b9\\u05d6, \\u05d4\\u05d7\\u05e0\\u05d5\\u05ea \\u05d4\\u05de\\u05d5\\u05d1\\u05d9\\u05dc\\u05d4 \\u05d1\\u05ea\\u05d7\\u05d5\\u05dd \\u05de\\u05db\\u05d9\\u05e8\\u05ea \\u05e0\\u05e2\\u05dc\\u05d9 \\u05e1\\u05e0\\u05d9\\u05e7\\u05e8\\u05e1. \\u05e8\\u05d5\\u05e6\\u05d4 \\u05dc\\u05e0\\u05e2\\u05d5\\u05dc \\u05e0\\u05e2\\u05dc\\u05d9 \\u05d2'\\u05d5\\u05e8\\u05d3\\u05df \\u05d7\\u05d3\\u05e9\\u05d5\\u05ea \\u05d1\\u05e1\\u05d8\\u05d9\\u05d9\\u05dc \\u05d9\\u05d5\\u05dd \\u05d9\\u05d5\\u05de\\u05d9? \\u05d4\\u05d6\\u05de\\u05d9\\u05e0\\u05d5 \\u05e2\\u05d5\\u05d3 \\u05d4\\u05d9\\u05d5\\u05dd!<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u05db\\u05de\\u05d4 \\u05d6\\u05de\\u05df \\u05d9\\u05e7\\u05d7 \\u05dc\\u05d0\\u05b7\\u05d2\\u05b0\\u05dc\\u05b4\\u05d9\\u05e9\\u05c1\\u05d5\\u05b9\\u05d6 \\u05dc\\u05d4\\u05d1\\u05d9\\u05d0 \\u05dc\\u05d9 \\u05d0\\u05ea \\u05d4\\u05d4\\u05d6\\u05de\\u05e0\\u05d5\\u05ea \\u05e9\\u05dc\\u05d9?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>\\u05d4\\u05e6\\u05d5\\u05d5\\u05ea \\u05e9\\u05dc\\u05e0\\u05d5 \\u05e2\\u05d5\\u05e9\\u05d4 \\u05d0\\u05ea \\u05db\\u05dc \\u05d4\\u05de\\u05d0\\u05de\\u05e6\\u05d9\\u05dd \\u05e2\\u05dc \\u05de\\u05e0\\u05ea \\u05dc\\u05e9\\u05dc\\u05d5\\u05d7 \\u05d0\\u05ea \\u05d4\\u05d4\\u05d6\\u05de\\u05e0\\u05d4 \\u05e9\\u05dc\\u05da \\u05dc\\u05d3\\u05dc\\u05ea \\u05d1\\u05d9\\u05ea\\u05da \\u05d1\\u05d4\\u05e7\\u05d3\\u05dd \\u05d4\\u05d0\\u05e4\\u05e9\\u05e8\\u05d9. \\u05d0\\u05e0\\u05d7\\u05e0\\u05d5 \\u05de\\u05d1\\u05d8\\u05d9\\u05d7\\u05d9\\u05dd \\u05e9\\u05d4\\u05d6\\u05de\\u05e0\\u05ea\\u05da \\u05ea\\u05e9\\u05dc\\u05d7 \\u05e2\\u05d3 24 \\u05e9\\u05e2\\u05d5\\u05ea \\u05de\\u05d9\\u05d5\\u05dd \\u05d1\\u05d9\\u05e6\\u05d5\\u05e2 \\u05d4\\u05d4\\u05d6\\u05de\\u05e0\\u05d4, \\u05d0\\u05d1\\u05dc \\u05d6\\u05d4 \\u05d9\\u05db\\u05d5\\u05dc \\u05dc\\u05e7\\u05d7\\u05ea \\u05d1\\u05d9\\u05df 6 \\u05dc19\\u00a0 \\u05d9\\u05de\\u05d9 \\u05e2\\u05e1\\u05e7\\u05d9\\u05dd \\u05e2\\u05d3 \\u05e9\\u05d6\\u05d4 \\u05de\\u05d2\\u05d9\\u05e2 \\u05d0\\u05dc\\u05d9\\u05d9\\u05da \\u05e2\\u05d3 \\u05d4\\u05d1\\u05d9\\u05ea. \\u05ea\\u05d5\\u05db\\u05dc \\u05d2\\u05dd \\u05dc\\u05d9\\u05e6\\u05d5\\u05e8 \\u05e7\\u05e9\\u05e8 \\u05e2\\u05dd \\u05e9\\u05d9\\u05e8\\u05d5\\u05ea \\u05d4\\u05dc\\u05e7\\u05d5\\u05d7\\u05d5\\u05ea \\u05e9\\u05dc\\u05e0\\u05d5 \\u05e2\\u05dc \\u05de\\u05e0\\u05ea \\u05dc\\u05d4\\u05d1\\u05d8\\u05d9\\u05d7 \\u05e9\\u05db\\u05dc \\u05d4\\u05d7\\u05e9\\u05e9\\u05d5\\u05ea \\u05e9\\u05dc\\u05da \\u05dc\\u05d2\\u05d1\\u05d9 \\u05d4\\u05de\\u05e9\\u05dc\\u05d5\\u05d7 \\u05d9\\u05e2\\u05dc\\u05de\\u05d5\\u00a0<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52372ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52372ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09631c5\" data-id=\"09631c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dba2990 elementor-widget elementor-widget-spacer\" data-id=\"dba2990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-640e1d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"640e1d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1f1d07\" data-id=\"f1f1d07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7a149d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7a149d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7276d2\" data-id=\"f7276d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>NIKE DUNK COLLECTION\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 \u2190 AIR JORDAN 1 COLLECTION\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 \u2190 NIKE DUNK COLLECTION\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 \u2190 AIR JORDAN 1 COLLECTION\u05dc\u05e6\u05e4\u05d9\u05d9\u05d4 \u05d1\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 \u2190 20,000 + \u05dc\u05e7\u05d5\u05d7\u05d5\u05ea \u05de\u05e8\u05d5\u05e6\u05d9\u05dd \u05d5\u05d7\u05d5\u05d6\u05e8\u05d9\u05dd \u00a05 \u05e9\u05e0\u05d5\u05ea \u05e0\u05d9\u05e1\u05d9\u05d5\u05df \u05de2017 \u05d7\u05d1\u05e8\u05d4 \u05d1\u05e2\u05f4\u05de \u05e8\u05db\u05d9\u05e9\u05d4 \u05de\u05d0\u05d5\u05d1\u05d8\u05d7\u05ea PCI , \u05e0\u05d5\u05d7\u05d4 \u05d5\u05e7\u05dc\u05d4 \u05e9\u05d9\u05e8\u05d5\u05ea \u05dc\u05e7\u05d5\u05d7\u05d5\u05ea \u05d6\u05de\u05d9\u05df \u05d5\u05de\u05d4\u05d9\u05e8 \u05d1\u05de\u05d9\u05d5\u05d7\u05d3 View All AIR JORDAN 1 \u05dc\u05db\u05e0\u05d9\u05e1\u05d4 \u05dc\u05e7\u05d5\u05dc\u05e7\u05e6\u05d9\u05d4 View All NIKE DUNK [&hellip;]<\/p>\n","protected":false},"author":26101,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-9380","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"acf":[],"_links":{"self":[{"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/pages\/9380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/users\/26101"}],"replies":[{"embeddable":true,"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/comments?post=9380"}],"version-history":[{"count":509,"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/pages\/9380\/revisions"}],"predecessor-version":[{"id":22858,"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/pages\/9380\/revisions\/22858"}],"wp:attachment":[{"href":"https:\/\/uglyshuzz.com\/he_il\/wp-json\/wp\/v2\/media?parent=9380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}